{"id":71652,"date":"2024-06-06T10:05:14","date_gmt":"2024-06-06T08:05:14","guid":{"rendered":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/non-classifiee\/cloches-5\/"},"modified":"2024-10-09T10:11:34","modified_gmt":"2024-10-09T08:11:34","slug":"cloches-5","status":"publish","type":"post","link":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/","title":{"rendered":"bells 5"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":62150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[96],"tags":[],"class_list":["post-71652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bells"],"acf":{"image_du_produit":62150,"galerie_dimages_du_produit":null,"description_du_produit":"","extra":"","custom_content":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>bells 5 - yves-piller.ch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"bells 5 - yves-piller.ch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/\" \/>\n<meta property=\"og:site_name\" content=\"yves-piller.ch\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T08:05:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-09T08:11:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/wp-content\/uploads\/2024\/06\/bouby-yves-piller-cloches-vieux-bois-5-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VCathyB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"VCathyB\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/\"},\"author\":{\"name\":\"VCathyB\",\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/#\\\/schema\\\/person\\\/0d84442678c47dc19d0c451a8af22891\"},\"headline\":\"bells 5\",\"datePublished\":\"2024-06-06T08:05:14+00:00\",\"dateModified\":\"2024-10-09T08:11:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/\"},\"wordCount\":1,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/bouby-yves-piller-cloches-vieux-bois-5-12.jpg\",\"articleSection\":[\"Bells\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/\",\"url\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/\",\"name\":\"bells 5 - yves-piller.ch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/bouby-yves-piller-cloches-vieux-bois-5-12.jpg\",\"datePublished\":\"2024-06-06T08:05:14+00:00\",\"dateModified\":\"2024-10-09T08:11:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/bouby-yves-piller-cloches-vieux-bois-5-12.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/bouby-yves-piller-cloches-vieux-bois-5-12.jpg\",\"width\":800,\"height\":565},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/bells\\\/cloches-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"bells 5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/#website\",\"url\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/\",\"name\":\"Yves Piller Vieux Bois Suisse Chez Bouby\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/#organization\",\"name\":\"Chez Bouby, Yves Piller Vieux Bois Suisse\",\"url\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-Chez-Bouby-RVB-1200dpi-copie.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-Chez-Bouby-RVB-1200dpi-copie.jpg\",\"width\":500,\"height\":302,\"caption\":\"Chez Bouby, Yves Piller Vieux Bois Suisse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/#\\\/schema\\\/person\\\/0d84442678c47dc19d0c451a8af22891\",\"name\":\"VCathyB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99c438c523c211ba0b93c1317c0f7a208468a29a590f0e1ef2cda7bff2a10e16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99c438c523c211ba0b93c1317c0f7a208468a29a590f0e1ef2cda7bff2a10e16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99c438c523c211ba0b93c1317c0f7a208468a29a590f0e1ef2cda7bff2a10e16?s=96&d=mm&r=g\",\"caption\":\"VCathyB\"},\"sameAs\":[\"https:\\\/\\\/dev.yves-piller.ch\"],\"url\":\"https:\\\/\\\/www.yves-piller.ch\\\/vieux-bois-suisse-bouby-yves-piller\\\/en\\\/author\\\/vcathyb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"bells 5 - yves-piller.ch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/","og_locale":"en_US","og_type":"article","og_title":"bells 5 - yves-piller.ch","og_url":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/","og_site_name":"yves-piller.ch","article_published_time":"2024-06-06T08:05:14+00:00","article_modified_time":"2024-10-09T08:11:34+00:00","og_image":[{"width":800,"height":565,"url":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/wp-content\/uploads\/2024\/06\/bouby-yves-piller-cloches-vieux-bois-5-12.jpg","type":"image\/jpeg"}],"author":"VCathyB","twitter_card":"summary_large_image","twitter_misc":{"Written by":"VCathyB"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/#article","isPartOf":{"@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/"},"author":{"name":"VCathyB","@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/#\/schema\/person\/0d84442678c47dc19d0c451a8af22891"},"headline":"bells 5","datePublished":"2024-06-06T08:05:14+00:00","dateModified":"2024-10-09T08:11:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/"},"wordCount":1,"commentCount":0,"publisher":{"@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/#organization"},"image":{"@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/wp-content\/uploads\/2024\/06\/bouby-yves-piller-cloches-vieux-bois-5-12.jpg","articleSection":["Bells"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/","url":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/","name":"bells 5 - yves-piller.ch","isPartOf":{"@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/#primaryimage"},"image":{"@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/wp-content\/uploads\/2024\/06\/bouby-yves-piller-cloches-vieux-bois-5-12.jpg","datePublished":"2024-06-06T08:05:14+00:00","dateModified":"2024-10-09T08:11:34+00:00","breadcrumb":{"@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/#primaryimage","url":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/wp-content\/uploads\/2024\/06\/bouby-yves-piller-cloches-vieux-bois-5-12.jpg","contentUrl":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/wp-content\/uploads\/2024\/06\/bouby-yves-piller-cloches-vieux-bois-5-12.jpg","width":800,"height":565},{"@type":"BreadcrumbList","@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/bells\/cloches-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/"},{"@type":"ListItem","position":2,"name":"bells 5"}]},{"@type":"WebSite","@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/#website","url":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/","name":"Yves Piller Vieux Bois Suisse Chez Bouby","description":"","publisher":{"@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/#organization","name":"Chez Bouby, Yves Piller Vieux Bois Suisse","url":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/#\/schema\/logo\/image\/","url":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/wp-content\/uploads\/2024\/06\/Logo-Chez-Bouby-RVB-1200dpi-copie.jpg","contentUrl":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/wp-content\/uploads\/2024\/06\/Logo-Chez-Bouby-RVB-1200dpi-copie.jpg","width":500,"height":302,"caption":"Chez Bouby, Yves Piller Vieux Bois Suisse"},"image":{"@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/#\/schema\/person\/0d84442678c47dc19d0c451a8af22891","name":"VCathyB","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/99c438c523c211ba0b93c1317c0f7a208468a29a590f0e1ef2cda7bff2a10e16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99c438c523c211ba0b93c1317c0f7a208468a29a590f0e1ef2cda7bff2a10e16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99c438c523c211ba0b93c1317c0f7a208468a29a590f0e1ef2cda7bff2a10e16?s=96&d=mm&r=g","caption":"VCathyB"},"sameAs":["https:\/\/dev.yves-piller.ch"],"url":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/author\/vcathyb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/posts\/71652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/comments?post=71652"}],"version-history":[{"count":1,"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/posts\/71652\/revisions"}],"predecessor-version":[{"id":71653,"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/posts\/71652\/revisions\/71653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/media\/62150"}],"wp:attachment":[{"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/media?parent=71652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/categories?post=71652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yves-piller.ch\/vieux-bois-suisse-bouby-yves-piller\/en\/wp-json\/wp\/v2\/tags?post=71652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}